{"id":176,"date":"2020-08-13T05:27:38","date_gmt":"2020-08-13T03:27:38","guid":{"rendered":"http:\/\/www.headshots-wiesbaden.com\/?page_id=176"},"modified":"2024-10-07T15:17:04","modified_gmt":"2024-10-07T13:17:04","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/www.headshots-wiesbaden.com\/en\/datenschutz\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"176\" class=\"elementor elementor-176\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78d3f99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78d3f99\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2efedb6a\" data-id=\"2efedb6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fd5d656 elementor-widget elementor-widget-text-editor\" data-id=\"5fd5d656\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<!-- wp:heading {\"level\":4} -->\n<h4>Datenschutzerkl\u00e4rung<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der Angie Meyer. Eine Nutzung der Internetseiten der Angie Meyer ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener Daten erforderlich werden. Ist die Verarbeitung personenbezogener Daten erforderlich und besteht f\u00fcr eine solche Verarbeitung keine gesetzliche Grundlage, holen wir generell eine Einwilligung der betroffenen Person ein.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die Verarbeitung personenbezogener Daten, beispielsweise des Namens, der Anschrift, E-Mail-Adresse oder Telefonnummer einer betroffenen Person, erfolgt stets im Einklang mit der Datenschutz-Grundverordnung und in \u00dcbereinstimmung mit den f\u00fcr die Angie Meyer geltenden landesspezifischen Datenschutzbestimmungen. Mittels dieser Datenschutzerkl\u00e4rung m\u00f6chte unser Unternehmen die \u00d6ffentlichkeit \u00fcber Art, Umfang und Zweck der von uns erhobenen, genutzten und verarbeiteten personenbezogenen Daten informieren. Ferner werden betroffene Personen mittels dieser Datenschutzerkl\u00e4rung \u00fcber die ihnen zustehenden Rechte aufgekl\u00e4rt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die Angie Meyer hat als f\u00fcr die Verarbeitung Verantwortlicher zahlreiche technische und organisatorische Ma\u00dfnahmen umgesetzt, um einen m\u00f6glichst l\u00fcckenlosen Schutz der \u00fcber diese Internetseite verarbeiteten personenbezogenen Daten sicherzustellen. Dennoch k\u00f6nnen Internetbasierte Daten\u00fcbertragungen grunds\u00e4tzlich Sicherheitsl\u00fccken aufweisen, sodass ein absoluter Schutz nicht gew\u00e4hrleistet werden kann. Aus diesem Grund steht es jeder betroffenen Person frei, personenbezogene Daten auch auf alternativen Wegen, beispielsweise telefonisch, an uns zu \u00fcbermitteln.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>1. Begriffsbestimmungen<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Die Datenschutzerkl\u00e4rung der Angie Meyer Photography beruht auf den Begrifflichkeiten, die durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber beim Erlass der Datenschutz-Grundverordnung (DS-GVO) verwendet wurden. Unsere Datenschutzerkl\u00e4rung soll sowohl f\u00fcr die \u00d6ffentlichkeit als auch f\u00fcr unsere Kunden und Gesch\u00e4ftspartner einfach lesbar und verst\u00e4ndlich sein. Um dies zu gew\u00e4hrleisten, m\u00f6chten wir vorab die verwendeten Begrifflichkeiten erl\u00e4utern.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Wir verwenden in dieser Datenschutzerkl\u00e4rung unter anderem die folgenden Begriffe:<\/p>\n<!-- \/wp:paragraph --><!-- wp:list -->\n<ul>\n<li>a)\u00a0\u00a0\u00a0 personenbezogene Daten Personenbezogene Daten sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \u201ebetroffene Person\u201c) beziehen. Als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung oder zu einem oder mehreren besonderen Merkmalen, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind, identifiziert werden kann.<\/li>\n<li>b)\u00a0\u00a0\u00a0 betroffene Person Betroffene Person ist jede identifizierte oder identifizierbare nat\u00fcrliche Person, deren personenbezogene Daten von dem f\u00fcr die Verarbeitung Verantwortlichen verarbeitet werden.<\/li>\n<li>c)\u00a0\u00a0\u00a0 Verarbeitung Verarbeitung ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/li>\n<li>d)\u00a0\u00a0\u00a0 Einschr\u00e4nkung der Verarbeitung Einschr\u00e4nkung der Verarbeitung ist die Markierung gespeicherter personenbezogener Daten mit dem Ziel, ihre k\u00fcnftige Verarbeitung einzuschr\u00e4nken.<\/li>\n<li>e)\u00a0\u00a0\u00a0 Profiling Profiling ist jede Art der automatisierten Verarbeitung personenbezogener Daten, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um bestimmte pers\u00f6nliche Aspekte, die sich auf eine nat\u00fcrliche Person beziehen, zu bewerten, insbesondere, um Aspekte bez\u00fcglich Arbeitsleistung, wirtschaftlicher Lage, Gesundheit, pers\u00f6nlicher Vorlieben, Interessen, Zuverl\u00e4ssigkeit, Verhalten, Aufenthaltsort oder Ortswechsel dieser nat\u00fcrlichen Person zu analysieren oder vorherzusagen.<\/li>\n<li>f)\u00a0\u00a0\u00a0\u00a0 Pseudonymisierung Pseudonymisierung ist die Verarbeitung personenbezogener Daten in einer Weise, auf welche die personenbezogenen Daten ohne Hinzuziehung zus\u00e4tzlicher Informationen nicht mehr einer spezifischen betroffenen Person zugeordnet werden k\u00f6nnen, sofern diese zus\u00e4tzlichen Informationen gesondert aufbewahrt werden und technischen und organisatorischen Ma\u00dfnahmen unterliegen, die gew\u00e4hrleisten, dass die personenbezogenen Daten nicht einer identifizierten oder identifizierbaren nat\u00fcrlichen Person zugewiesen werden.<\/li>\n<li>g)\u00a0\u00a0\u00a0 Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher ist die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet. Sind die Zwecke und Mittel dieser Verarbeitung durch das Unionsrecht oder das Recht der Mitgliedstaaten vorgegeben, so kann der Verantwortliche beziehungsweise k\u00f6nnen die bestimmten Kriterien seiner Benennung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten vorgesehen werden.<\/li>\n<li>h)\u00a0\u00a0\u00a0 Auftragsverarbeiter Auftragsverarbeiter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die personenbezogene Daten im Auftrag des Verantwortlichen verarbeitet.<\/li>\n<li>i)\u00a0\u00a0\u00a0\u00a0\u00a0 Empf\u00e4nger Empf\u00e4nger ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, der personenbezogene Daten offengelegt werden, unabh\u00e4ngig davon, ob es sich bei ihr um einen Dritten handelt oder nicht. Beh\u00f6rden, die im Rahmen eines bestimmten Untersuchungsauftrags nach dem Unionsrecht oder dem Recht der Mitgliedstaaten m\u00f6glicherweise personenbezogene Daten erhalten, gelten jedoch nicht als Empf\u00e4nger.<\/li>\n<li>j)\u00a0\u00a0\u00a0\u00a0\u00a0 Dritter Dritter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle au\u00dfer der betroffenen Person, dem Verantwortlichen, dem Auftragsverarbeiter und den Personen, die unter der unmittelbaren Verantwortung des Verantwortlichen oder des Auftragsverarbeiters befugt sind, die personenbezogenen Daten zu verarbeiten.<\/li>\n<li>k)\u00a0\u00a0\u00a0 Einwilligung Einwilligung ist jede von der betroffenen Person freiwillig f\u00fcr den bestimmten Fall in informierter Weise und unmissverst\u00e4ndlich abgegebene Willensbekundung in Form einer Erkl\u00e4rung oder einer sonstigen eindeutigen best\u00e4tigenden Handlung, mit der die betroffene Person zu verstehen gibt, dass sie mit der Verarbeitung der sie betreffenden personenbezogenen Daten einverstanden ist.<\/li>\n<\/ul>\n<!-- \/wp:list --><!-- wp:heading {\"level\":4} -->\n<h4>2. Name und Anschrift des f\u00fcr die Verarbeitung Verantwortlichen<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Verantwortlicher im Sinne der Datenschutz-Grundverordnung, sonstiger in den Mitgliedstaaten der Europ\u00e4ischen Union geltenden Datenschutzgesetze und anderer Bestimmungen mit datenschutzrechtlichem Charakter ist die:<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Angela Meyer<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Simone-Veil-Stra\u00dfe 3<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>65197 Wiesbaden<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Deutschland<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Tel.: 0151-52411692<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>E-Mail: angie@headshots-wiesbaden.com<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Website: www.headshots-wiesbaden.com<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>3. Cookies<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Die Internetseiten der Angie Meyer Photography verwenden Cookies. Cookies sind Textdateien, welche \u00fcber einen Internetbrowser auf einem Computersystem abgelegt und gespeichert werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Zahlreiche Internetseiten und Server verwenden Cookies. Viele Cookies enthalten eine sogenannte Cookie-ID. Eine Cookie-ID ist eine eindeutige Kennung des Cookies. Sie besteht aus einer Zeichenfolge, durch welche Internetseiten und Server dem konkreten Internetbrowser zugeordnet werden k\u00f6nnen, in dem das Cookie gespeichert wurde. Dies erm\u00f6glicht es den besuchten Internetseiten und Servern, den individuellen Browser der betroffenen Person von anderen Internetbrowsern, die andere Cookies enthalten, zu unterscheiden. Ein bestimmter Internetbrowser kann \u00fcber die eindeutige Cookie-ID wiedererkannt und identifiziert werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Durch den Einsatz von Cookies kann die Angie Meyer den Nutzern dieser Internetseite nutzerfreundlichere Services bereitstellen, die ohne die Cookie-Setzung nicht m\u00f6glich w\u00e4ren.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Mittels eines Cookies k\u00f6nnen die Informationen und Angebote auf unserer Internetseite im Sinne des Benutzers optimiert werden. Cookies erm\u00f6glichen uns, wie bereits erw\u00e4hnt, die Benutzer unserer Internetseite wiederzuerkennen. Zweck dieser Wiedererkennung ist es, den Nutzern die Verwendung unserer Internetseite zu erleichtern. Der Benutzer einer Internetseite, die Cookies verwendet, muss beispielsweise nicht bei jedem Besuch der Internetseite erneut seine Zugangsdaten eingeben, weil dies von der Internetseite und dem auf dem Computersystem des Benutzers abgelegten Cookie \u00fcbernommen wird. Ein weiteres Beispiel ist das Cookie eines Warenkorbes im Online-Shop. Der Online-Shop merkt sich die Artikel, die ein Kunde in den virtuellen Warenkorb gelegt hat, \u00fcber ein Cookie.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Ferner k\u00f6nnen bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden. Dies ist in allen g\u00e4ngigen Internetbrowsern m\u00f6glich. Deaktiviert die betroffene Person die Setzung von Cookies in dem genutzten Internetbrowser, sind unter Umst\u00e4nden nicht alle Funktionen unserer Internetseite vollumf\u00e4nglich nutzbar.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>4. Erfassung von allgemeinen Daten und Informationen<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Die Internetseite der Angie Meyer erfasst mit jedem Aufruf der Internetseite durch eine betroffene Person oder ein automatisiertes System eine Reihe von allgemeinen Daten und Informationen. Diese allgemeinen Daten und Informationen werden in den Logfiles des Servers gespeichert. Erfasst werden k\u00f6nnen die (1) verwendeten Browsertypen und Versionen, (2) das vom zugreifenden System verwendete Betriebssystem, (3) die Internetseite, von welcher ein zugreifendes System auf unsere Internetseite gelangt (sogenannte Referrer), (4) die Unterwebseiten, welche \u00fcber ein zugreifendes System auf unserer Internetseite angesteuert werden, (5) das Datum und die Uhrzeit eines Zugriffs auf die Internetseite, (6) eine Internet-Protokoll-Adresse (IP-Adresse), (7) der Internet-Service-Provider des zugreifenden Systems und (8) sonstige \u00e4hnliche Daten und Informationen, die der Gefahrenabwehr im Falle von Angriffen auf unsere informationstechnologischen Systeme dienen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Bei der Nutzung dieser allgemeinen Daten und Informationen zieht die Angie Meyer keine R\u00fcckschl\u00fcsse auf die betroffene Person. Diese Informationen werden vielmehr ben\u00f6tigt, um (1) die Inhalte unserer Internetseite korrekt auszuliefern, (2) die Inhalte unserer Internetseite sowie die Werbung f\u00fcr diese zu optimieren, (3) die dauerhafte Funktionsf\u00e4higkeit unserer informationstechnologischen Systeme und der Technik unserer Internetseite zu gew\u00e4hrleisten sowie (4) um Strafverfolgungsbeh\u00f6rden im Falle eines Cyberangriffes die zur Strafverfolgung notwendigen Informationen bereitzustellen. Diese anonym erhobenen Daten und Informationen werden durch die Angie Meyer daher einerseits statistisch und ferner mit dem Ziel ausgewertet, den Datenschutz und die Datensicherheit in unserem Unternehmen zu erh\u00f6hen, um letztlich ein optimales Schutzniveau f\u00fcr die von uns verarbeiteten personenbezogenen Daten sicherzustellen. Die anonymen Daten der Server-Logfiles werden getrennt von allen durch eine betroffene Person angegebenen personenbezogenen Daten gespeichert.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>5. Registrierung auf unserer Internetseite<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Die betroffene Person hat die M\u00f6glichkeit, sich auf der Internetseite des f\u00fcr die Verarbeitung Verantwortlichen unter Angabe von personenbezogenen Daten zu registrieren. Welche personenbezogenen Daten dabei an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelt werden, ergibt sich aus der jeweiligen Eingabemaske, die f\u00fcr die Registrierung verwendet wird. Die von der betroffenen Person eingegebenen personenbezogenen Daten werden ausschlie\u00dflich f\u00fcr die interne Verwendung bei dem f\u00fcr die Verarbeitung Verantwortlichen und f\u00fcr eigene Zwecke erhoben und gespeichert. Der f\u00fcr die Verarbeitung Verantwortliche kann die Weitergabe an einen oder mehrere Auftragsverarbeiter, beispielsweise einen Paketdienstleister, veranlassen, der die personenbezogenen Daten ebenfalls ausschlie\u00dflich f\u00fcr eine interne Verwendung, die dem f\u00fcr die Verarbeitung Verantwortlichen zuzurechnen ist, nutzt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Durch eine Registrierung auf der Internetseite des f\u00fcr die Verarbeitung Verantwortlichen wird ferner die vom Internet-Service-Provider (ISP) der betroffenen Person vergebene IP-Adresse, das Datum sowie die Uhrzeit der Registrierung gespeichert. Die Speicherung dieser Daten erfolgt vor dem Hintergrund, dass nur so der Missbrauch unserer Dienste verhindert werden kann, und diese Daten im Bedarfsfall erm\u00f6glichen, begangene Straftaten aufzukl\u00e4ren. Insofern ist die Speicherung dieser Daten zur Absicherung des f\u00fcr die Verarbeitung Verantwortlichen erforderlich. Eine Weitergabe dieser Daten an Dritte erfolgt grunds\u00e4tzlich nicht, sofern keine gesetzliche Pflicht zur Weitergabe besteht oder die Weitergabe der Strafverfolgung dient.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die Registrierung der betroffenen Person unter freiwilliger Angabe personenbezogener Daten dient dem f\u00fcr die Verarbeitung Verantwortlichen dazu, der betroffenen Person Inhalte oder Leistungen anzubieten, die aufgrund der Natur der Sache nur registrierten Benutzern angeboten werden k\u00f6nnen. Registrierten Personen steht die M\u00f6glichkeit frei, die bei der Registrierung angegebenen personenbezogenen Daten jederzeit abzu\u00e4ndern oder vollst\u00e4ndig aus dem Datenbestand des f\u00fcr die Verarbeitung Verantwortlichen l\u00f6schen zu lassen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche erteilt jeder betroffenen Person jederzeit auf Anfrage Auskunft dar\u00fcber, welche personenbezogenen Daten \u00fcber die betroffene Person gespeichert sind. Ferner berichtigt oder l\u00f6scht der f\u00fcr die Verarbeitung Verantwortliche personenbezogene Daten auf Wunsch oder Hinweis der betroffenen Person, soweit dem keine gesetzlichen Aufbewahrungspflichten entgegenstehen. Die Gesamtheit der Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen stehen der betroffenen Person in diesem Zusammenhang als Ansprechpartner zur Verf\u00fcgung.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>6. Abonnement unseres Newsletters<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Auf der Internetseite der Angie Meyer wird den Benutzern die M\u00f6glichkeit einger\u00e4umt, den Newsletter unseres Unternehmens zu abonnieren. Welche personenbezogenen Daten bei der Bestellung des Newsletters an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelt werden, ergibt sich aus der hierzu verwendeten Eingabemaske.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die Angie Meyer informiert ihre Kunden und Gesch\u00e4ftspartner in regelm\u00e4\u00dfigen Abst\u00e4nden im Wege eines Newsletters \u00fcber Angebote des Unternehmens. Der Newsletter unseres Unternehmens kann von der betroffenen Person grunds\u00e4tzlich nur dann empfangen werden, wenn (1) die betroffene Person \u00fcber eine g\u00fcltige E-Mail-Adresse verf\u00fcgt und (2) die betroffene Person sich f\u00fcr den Newsletterversand registriert. An die von einer betroffenen Person erstmalig f\u00fcr den Newsletterversand eingetragene E-Mail-Adresse wird aus rechtlichen Gr\u00fcnden eine Best\u00e4tigungsmail im Double-Opt-In-Verfahren versendet. Diese Best\u00e4tigungsmail dient der \u00dcberpr\u00fcfung, ob der Inhaber der E-Mail-Adresse als betroffene Person den Empfang des Newsletters autorisiert hat.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Bei der Anmeldung zum Newsletter speichern wir ferner die vom Internet-Service-Provider (ISP) vergebene IP-Adresse des von der betroffenen Person zum Zeitpunkt der Anmeldung verwendeten Computersystems sowie das Datum und die Uhrzeit der Anmeldung. Die Erhebung dieser Daten ist erforderlich, um den(m\u00f6glichen) Missbrauch der E-Mail-Adresse einer betroffenen Person zu einem sp\u00e4teren Zeitpunkt nachvollziehen zu k\u00f6nnen und dient deshalb der rechtlichen Absicherung des f\u00fcr die Verarbeitung Verantwortlichen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die im Rahmen einer Anmeldung zum Newsletter erhobenen personenbezogenen Daten werden ausschlie\u00dflich zum Versand unseres Newsletters verwendet. Ferner k\u00f6nnten Abonnenten des Newsletters per E-Mail informiert werden, sofern dies f\u00fcr den Betrieb des Newsletter-Dienstes oder eine diesbez\u00fcgliche Registrierung erforderlich ist, wie dies im Falle von \u00c4nderungen am Newsletterangebot oder bei der Ver\u00e4nderung der technischen Gegebenheiten der Fall sein k\u00f6nnte. Es erfolgt keine Weitergabe der im Rahmen des Newsletter-Dienstes erhobenen personenbezogenen Daten an Dritte. Das Abonnement unseres Newsletters kann durch die betroffene Person jederzeit gek\u00fcndigt werden. Die Einwilligung in die Speicherung personenbezogener Daten, die die betroffene Person uns f\u00fcr den Newsletterversand erteilt hat, kann jederzeit widerrufen werden. Zum Zwecke des Widerrufs der Einwilligung findet sich in jedem Newsletter ein entsprechender Link. Ferner besteht die M\u00f6glichkeit, sich jederzeit auch direkt auf der Internetseite des f\u00fcr die Verarbeitung Verantwortlichen vom Newsletterversand abzumelden oder dies dem f\u00fcr die Verarbeitung Verantwortlichen auf andere Weise mitzuteilen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>7. Newsletter-Tracking<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Die Newsletter der Angie Meyer enthalten sogenannte Z\u00e4hlpixel. Ein Z\u00e4hlpixel ist eine Miniaturgrafik, die in solche E-Mails eingebettet wird, welche im HTML-Format versendet werden, um eine Logdatei-Aufzeichnung und eine Logdatei-Analyse zu erm\u00f6glichen. Dadurch kann eine statistische Auswertung des Erfolges oder Misserfolges von Online-Marketing-Kampagnen durchgef\u00fchrt werden. Anhand des eingebetteten Z\u00e4hlpixels kann die Angie Meyer erkennen, ob und wann eine E-Mail von einer betroffenen Person ge\u00f6ffnet wurde und welche in der E-Mail befindlichen Links von der betroffenen Person aufgerufen wurden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Solche \u00fcber die in den Newslettern enthaltenen Z\u00e4hlpixel erhobenen personenbezogenen Daten, werden von dem f\u00fcr die Verarbeitung Verantwortlichen gespeichert und ausgewertet, um den Newsletterversand zu optimieren und den Inhalt zuk\u00fcnftiger Newsletter noch besser den Interessen der betroffenen Person anzupassen. Diese personenbezogenen Daten werden nicht an Dritte weitergegeben. Betroffene Personen sind jederzeit berechtigt, die diesbez\u00fcgliche gesonderte, \u00fcber das Double-Opt-In-Verfahren abgegebene Einwilligungserkl\u00e4rung zu widerrufen. Nach einem Widerruf werden diese personenbezogenen Daten von dem f\u00fcr die Verarbeitung Verantwortlichen gel\u00f6scht. Eine Abmeldung vom Erhalt des Newsletters deutet die Angie Meyer automatisch als Widerruf.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>8. Kontaktm\u00f6glichkeit \u00fcber die Internetseite<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Die Internetseite der Angie Meyer enth\u00e4lt aufgrund von gesetzlichen Vorschriften Angaben, die eine schnelle elektronische Kontaktaufnahme zu unserem Unternehmen sowie eine unmittelbare Kommunikation mit uns erm\u00f6glichen, was ebenfalls eine allgemeine Adresse der sogenannten elektronischen Post (E-Mail-Adresse) umfasst. Sofern eine betroffene Person per E-Mail oder \u00fcber ein Kontaktformular den Kontakt mit dem f\u00fcr die Verarbeitung Verantwortlichen aufnimmt, werden die von der betroffenen Person \u00fcbermittelten personenbezogenen Daten automatisch gespeichert. Solche auf freiwilliger Basis von einer betroffenen Person an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelten personenbezogenen Daten werden f\u00fcr Zwecke der Bearbeitung oder der Kontaktaufnahme zur betroffenen Person gespeichert. Es erfolgt keine Weitergabe dieser personenbezogenen Daten an Dritte.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>9. Kommentarfunktion im Blog auf der Internetseite<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Die Angie Meyer bietet den Nutzern auf einem Blog, der sich auf der Internetseite des f\u00fcr die Verarbeitung Verantwortlichen befindet, die M\u00f6glichkeit, individuelle Kommentare zu einzelnen Blog-Beitr\u00e4gen zu hinterlassen. Ein Blog ist ein auf einer Internetseite gef\u00fchrtes, in der Regel \u00f6ffentlich einsehbares Portal, in welchem eine oder mehrere Personen, die Blogger oder Web-Blogger genannt werden, Artikel posten oder Gedanken in sogenannten Blogposts niederschreiben k\u00f6nnen. Die Blogposts k\u00f6nnen in der Regel von Dritten kommentiert werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Hinterl\u00e4sst eine betroffene Person einen Kommentar in dem auf dieser Internetseite ver\u00f6ffentlichten Blog, werden neben den von der betroffenen Person hinterlassenen Kommentaren auch Angaben zum Zeitpunkt der Kommentareingabe sowie zu dem von der betroffenen Person gew\u00e4hlten Nutzernamen (Pseudonym) gespeichert und ver\u00f6ffentlicht. Ferner wird die vom Internet-Service-Provider (ISP) der betroffenen Person vergebene IP-Adresse mitprotokolliert. Diese Speicherung der IP-Adresse erfolgt aus Sicherheitsgr\u00fcnden und f\u00fcr den Fall, dass die betroffene Person durch einen abgegebenen Kommentar die Rechte Dritter verletzt oder rechtswidrige Inhalte postet. Die Speicherung dieser personenbezogenen Daten erfolgt daher im eigenen Interesse des f\u00fcr die Verarbeitung Verantwortlichen, damit sich dieser im Falle einer Rechtsverletzung gegebenenfalls exkulpieren k\u00f6nnte. Es erfolgt keine Weitergabe dieser erhobenen personenbezogenen Daten an Dritte, sofern eine solche Weitergabe nicht gesetzlich vorgeschrieben ist oder der Rechtsverteidigung des f\u00fcr die Verarbeitung Verantwortlichen dient.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>10. Abonnement von Kommentaren im Blog auf der Internetseite<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Die im Blog der Angie Meyer abgegebenen Kommentare k\u00f6nnen grunds\u00e4tzlich von Dritten abonniert werden. Insbesondere besteht die M\u00f6glichkeit, dass ein Kommentator die seinem Kommentar nachfolgenden Kommentare zu einem bestimmten Blog-Beitrag abonniert.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Sofern sich eine betroffene Person f\u00fcr die Option entscheidet, Kommentare zu abonnieren, versendet der f\u00fcr die Verarbeitung Verantwortliche eine automatische Best\u00e4tigungsmail, um im Double-Opt-In-Verfahren zu \u00fcberpr\u00fcfen, ob sich wirklich der Inhaber der angegebenen E-Mail-Adresse f\u00fcr diese Option entschieden hat. Die Option zum Abonnement von Kommentaren kann jederzeit beendet werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>11. Routinem\u00e4\u00dfige L\u00f6schung und Sperrung von personenbezogenen Daten<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche verarbeitet und speichert personenbezogene Daten der betroffenen Person nur f\u00fcr den Zeitraum, der zur Erreichung des Speicherungszwecks erforderlich ist oder sofern dies durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einen anderen Gesetzgeber in Gesetzen oder Vorschriften, welchen der f\u00fcr die Verarbeitung Verantwortliche unterliegt, vorgesehen wurde.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Entf\u00e4llt der Speicherungszweck oder l\u00e4uft eine vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einem anderen zust\u00e4ndigen Gesetzgeber vorgeschriebene Speicherfrist ab, werden die personenbezogenen Daten routinem\u00e4\u00dfig und entsprechend den gesetzlichen Vorschriften gesperrt oder gel\u00f6scht.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>12. Rechte der betroffenen Person<\/h4>\n<!-- \/wp:heading --><!-- wp:list -->\n<ul>\n<li>a)\u00a0\u00a0\u00a0 Recht auf Best\u00e4tigung Jede betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber einger\u00e4umte Recht, von dem f\u00fcr die Verarbeitung Verantwortlichen eine Best\u00e4tigung dar\u00fcber zu verlangen, ob sie betreffende personenbezogene Daten verarbeitet werden. M\u00f6chte eine betroffene Person dieses Best\u00e4tigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<li>b)\u00a0\u00a0\u00a0 Recht auf Auskunft Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, jederzeit von dem f\u00fcr die Verarbeitung Verantwortlichen unentgeltliche Auskunft \u00fcber die zu seiner Person gespeicherten personenbezogenen Daten und eine Kopie dieser Auskunft zu erhalten. Ferner hat der Europ\u00e4ische Richtlinien- und Verordnungsgeber der betroffenen Person Auskunft \u00fcber folgende Informationen zugestanden:\n<ul>\n<li>die Verarbeitungszwecke<\/li>\n<li>die Kategorien personenbezogener Daten, die verarbeitet werden<\/li>\n<li>die Empf\u00e4nger oder Kategorien von Empf\u00e4ngern, gegen\u00fcber denen die personenbezogenen Daten offengelegt worden sind oder noch offengelegt werden, insbesondere bei Empf\u00e4ngern in Drittl\u00e4ndern oder bei internationalen Organisationen<\/li>\n<li>falls m\u00f6glich die geplante Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden, oder, falls dies nicht m\u00f6glich ist, die Kriterien f\u00fcr die Festlegung dieser Dauer<\/li>\n<li>das Bestehen eines Rechts auf Berichtigung oder L\u00f6schung der sie betreffenden personenbezogenen Daten oder auf Einschr\u00e4nkung der Verarbeitung durch den Verantwortlichen oder eines Widerspruchsrechts gegen diese Verarbeitung<\/li>\n<li>das Bestehen eines Beschwerderechts bei einer Aufsichtsbeh\u00f6rde<\/li>\n<li>wenn die personenbezogenen Daten nicht bei der betroffenen Person erhoben werden: Alle verf\u00fcgbaren Informationen \u00fcber die Herkunft der Daten<\/li>\n<li>das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs.1 und 4 DS-GVO und \u2014 zumindest in diesen F\u00e4llen \u2014 aussagekr\u00e4ftige Informationen \u00fcber die involvierte Logik sowie die Tragweite und die angestrebten Auswirkungen einer derartigen Verarbeitung f\u00fcr die betroffene Person<\/li>\n<\/ul>\nFerner steht der betroffenen Person ein Auskunftsrecht dar\u00fcber zu, ob personenbezogene Daten an ein Drittland oder an eine internationale Organisation \u00fcbermittelt wurden. Sofern dies der Fall ist, so steht der betroffenen Person im \u00dcbrigen das Recht zu, Auskunft \u00fcber die geeigneten Garantien im Zusammenhang mit der \u00dcbermittlung zu erhalten. M\u00f6chte eine betroffene Person dieses Auskunftsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<li>c)\u00a0\u00a0\u00a0 Recht auf Berichtigung Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die unverz\u00fcgliche Berichtigung sie betreffender unrichtiger personenbezogener Daten zu verlangen. Ferner steht der betroffenen Person das Recht zu, unter Ber\u00fccksichtigung der Zwecke der Verarbeitung, die Vervollst\u00e4ndigung unvollst\u00e4ndiger personenbezogener Daten \u2014 auch mittels einer erg\u00e4nzenden Erkl\u00e4rung \u2014 zu verlangen. M\u00f6chte eine betroffene Person dieses Berichtigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<li>d)\u00a0\u00a0\u00a0 Recht auf L\u00f6schung (Recht auf Vergessen werden) Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen zu verlangen, dass die sie betreffenden personenbezogenen Daten unverz\u00fcglich gel\u00f6scht werden, sofern einer der folgenden Gr\u00fcnde zutrifft und soweit die Verarbeitung nicht erforderlich ist:\n<ul>\n<li>Die personenbezogenen Daten wurden f\u00fcr solche Zwecke erhoben oder auf sonstige Weise verarbeitet, f\u00fcr welche sie nicht mehr notwendig sind.<\/li>\n<li>Die betroffene Person widerruft ihre Einwilligung, auf die sich die Verarbeitung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung.<\/li>\n<li>Die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 1 DS-GVO Widerspruch gegen die Verarbeitung ein, und es liegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 2 DS-GVO Widerspruch gegen die Verarbeitung ein.<\/li>\n<li>Die personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet.<\/li>\n<li>Die L\u00f6schung der personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem der Verantwortliche unterliegt.<\/li>\n<li>Die personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Art. 8 Abs. 1 DS-GVO erhoben.<\/li>\n<\/ul>\nSofern einer der oben genannten Gr\u00fcnde zutrifft und eine betroffene Person die L\u00f6schung von personenbezogenen Daten, die bei der Angie Meyer gespeichert sind, veranlassen m\u00f6chte, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Mitarbeiter der Angie Meyer wird veranlassen, dass dem L\u00f6schverlangen unverz\u00fcglich nachgekommen wird. Wurden die personenbezogenen Daten von der Angie Meyer \u00f6ffentlich gemacht und ist unser Unternehmen als Verantwortlicher gem\u00e4\u00df Art. 17 Abs. 1 DS-GVO zur L\u00f6schung der personenbezogenen Daten verpflichtet, so trifft die Angie Meyer unter Ber\u00fccksichtigung der verf\u00fcgbaren Technologie und der Implementierungskosten angemessene Ma\u00dfnahmen, auch technischer Art, um andere f\u00fcr die Datenverarbeitung Verantwortliche, welche die ver\u00f6ffentlichten personenbezogenen Daten verarbeiten, dar\u00fcber in Kenntnis zu setzen, dass die betroffene Person von diesen anderen f\u00fcr die Datenverarbeitung Verantwortlichen die L\u00f6schung s\u00e4mtlicher Links zu diesen personenbezogenen Daten oder von Kopien oder Replikationen dieser personenbezogenen Daten verlangt hat, soweit die Verarbeitung nicht erforderlich ist. Der Mitarbeiter der Angie Meyer wird im Einzelfall das Notwendige veranlassen.<\/li>\n<li>e)\u00a0\u00a0\u00a0 Recht auf Einschr\u00e4nkung der Verarbeitung Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen die Einschr\u00e4nkung der Verarbeitung zu verlangen, wenn eine der folgenden Voraussetzungen gegeben ist:\n<ul>\n<li>Die Richtigkeit der personenbezogenen Daten wird von der betroffenen Person bestritten, und zwar f\u00fcr eine Dauer, die es dem Verantwortlichen erm\u00f6glicht, die Richtigkeit der personenbezogenen Daten zu \u00fcberpr\u00fcfen.<\/li>\n<li>Die Verarbeitung ist unrechtm\u00e4\u00dfig, die betroffene Person lehnt die L\u00f6schung der personenbezogenen Daten ab und verlangt stattdessen die Einschr\u00e4nkung der Nutzung der personenbezogenen Daten.<\/li>\n<li>Der Verantwortliche ben\u00f6tigt die personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht l\u00e4nger, die betroffene Person ben\u00f6tigt sie jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/li>\n<li>Die betroffene Person hat Widerspruch gegen die Verarbeitung gem. Art. 21 Abs. 1 DS-GVO eingelegt und es steht noch nicht fest, ob die berechtigten Gr\u00fcnde des Verantwortlichen gegen\u00fcber denen der betroffenen Person \u00fcberwiegen.<\/li>\n<\/ul>\nSofern eine der oben genannten Voraussetzungen gegeben ist und eine betroffene Person die Einschr\u00e4nkung von personenbezogenen Daten, die bei der Angie Meyer gespeichert sind, verlangen m\u00f6chte, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Mitarbeiter der Angie Meyer wird die Einschr\u00e4nkung der Verarbeitung veranlassen.<\/li>\n<li>f)\u00a0\u00a0\u00a0\u00a0 Recht auf Daten\u00fcbertragbarkeit Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die sie betreffenden personenbezogenen Daten, welche durch die betroffene Person einem Verantwortlichen bereitgestellt wurden, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten. Sie hat au\u00dferdem das Recht, diese Daten einem anderen Verantwortlichen ohne Behinderung durch den Verantwortlichen, dem die personenbezogenen Daten bereitgestellt wurden, zu \u00fcbermitteln, sofern die Verarbeitung auf der Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO oder auf einem Vertrag gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe b DS-GVO beruht und die Verarbeitung mithilfe automatisierter Verfahren erfolgt, sofern die Verarbeitung nicht f\u00fcr die Wahrnehmung einer Aufgabe erforderlich ist, die im \u00f6ffentlichen Interesse liegt oder in Aus\u00fcbung \u00f6ffentlicher Gewalt erfolgt, welche dem Verantwortlichen \u00fcbertragen wurde. Ferner hat die betroffene Person bei der Aus\u00fcbung ihres Rechts auf Daten\u00fcbertragbarkeit gem\u00e4\u00df Art. 20 Abs. 1 DS-GVO das Recht, zu erwirken, dass die personenbezogenen Daten direkt von einem Verantwortlichen an einen anderen Verantwortlichen \u00fcbermittelt werden, soweit dies technisch machbar ist und sofern hiervon nicht die Rechte und Freiheiten anderer Personen beeintr\u00e4chtigt werden. Zur Geltendmachung des Rechts auf Daten\u00fcbertragbarkeit kann sich die betroffene Person jederzeit an einen Mitarbeiter der Angie Meyer wenden.<\/li>\n<li>g)\u00a0\u00a0\u00a0 Recht auf Widerspruch Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung sie betreffender personenbezogener Daten, die aufgrund von Art. 6 Abs. 1 Buchstaben e oder f DS-GVO erfolgt, Widerspruch einzulegen. Dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Die Angie Meyer verarbeitet die personenbezogenen Daten im Falle des Widerspruchs nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die den Interessen, Rechten und Freiheiten der betroffenen Person \u00fcberwiegen, oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen. Verarbeitet die Angie Meyer personenbezogene Daten, um Direktwerbung zu betreiben, so hat die betroffene Person das Recht, jederzeit Widerspruch gegen die Verarbeitung der personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen. Dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht. Widerspricht die betroffene Person gegen\u00fcber der Angie Meyer der Verarbeitung f\u00fcr Zwecke der Direktwerbung, so wird die Angie Meyer die personenbezogenen Daten nicht mehr f\u00fcr diese Zwecke verarbeiten. Zudem hat die betroffene Person das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, gegen die sie betreffende Verarbeitung personenbezogener Daten, die bei der Angie Meyer zu wissenschaftlichen oder historischen Forschungszwecken oder zu statistischen Zwecken gem\u00e4\u00df Art. 89 Abs. 1 DS-GVO erfolgen, Widerspruch einzulegen, es sei denn, eine solche Verarbeitung ist zur Erf\u00fcllung einer im \u00f6ffentlichen Interesse liegenden Aufgabe erforderlich. Zur Aus\u00fcbung des Rechts auf Widerspruch kann sich die betroffene Person direkt an jeden Mitarbeiter der Angie Meyer oder einen anderen Mitarbeiter wenden. Der betroffenen Person steht es ferner frei, im Zusammenhang mit der Nutzung von Diensten der Informationsgesellschaft, ungeachtet der Richtlinie 2002\/58\/EG, ihr Widerspruchsrecht mittels automatisierter Verfahren auszu\u00fcben, bei denen technische Spezifikationen verwendet werden.<\/li>\n<li>h)\u00a0\u00a0\u00a0 Automatisierte Entscheidungen im Einzelfall einschlie\u00dflich Profiling Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung \u2014 einschlie\u00dflich Profiling \u2014 beruhenden Entscheidung unterworfen zu werden, die ihr gegen\u00fcber rechtliche Wirkung entfaltet oder sie in \u00e4hnlicher Weise erheblich beeintr\u00e4chtigt, sofern die Entscheidung (1) nicht f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich ist, oder (2) aufgrund von Rechtsvorschriften der Union oder der Mitgliedstaaten, denen der Verantwortliche unterliegt, zul\u00e4ssig ist und diese Rechtsvorschriften angemessene Ma\u00dfnahmen zur Wahrung der Rechte und Freiheiten sowie der berechtigten Interessen der betroffenen Person enthalten oder (3) mit ausdr\u00fccklicher Einwilligung der betroffenen Person erfolgt. Ist die Entscheidung (1) f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich oder (2) erfolgt sie mit ausdr\u00fccklicher Einwilligung der betroffenen Person, trifft die Angie Meyer angemessene Ma\u00dfnahmen, um die Rechte und Freiheiten sowie die berechtigten Interessen der betroffenen Person zu wahren, wozu mindestens das Recht auf Erwirkung des Eingreifens einer Person seitens des Verantwortlichen, auf Darlegung des eigenen Standpunkts und auf Anfechtung der Entscheidung geh\u00f6rt. M\u00f6chte die betroffene Person Rechte mit Bezug auf automatisierte Entscheidungen geltend machen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<li>i)\u00a0\u00a0\u00a0\u00a0\u00a0 Recht auf Widerruf einer datenschutzrechtlichen Einwilligung Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, eine Einwilligung zur Verarbeitung personenbezogener Daten jederzeit zu widerrufen. M\u00f6chte die betroffene Person ihr Recht auf Widerruf einer Einwilligung geltend machen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<\/ul>\n<!-- \/wp:list --><!-- wp:heading {\"level\":4} -->\n<h4>13. Datenschutzbestimmungen zu Einsatz und Verwendung von Facebook<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten des Unternehmens Facebook integriert. Facebook ist ein soziales Netzwerk.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Ein soziales Netzwerk ist ein im Internet betriebener sozialer Treffpunkt, eine Online-Gemeinschaft, die es den Nutzern in der Regel erm\u00f6glicht, untereinander zu kommunizieren und im virtuellen Raum zu interagieren. Ein soziales Netzwerk kann als Plattform zum Austausch von Meinungen und Erfahrungen dienen oder erm\u00f6glicht es der Internetgemeinschaft, pers\u00f6nliche oder unternehmensbezogene Informationen bereitzustellen. Facebook erm\u00f6glicht den Nutzern des sozialen Netzwerkes unter anderem die Erstellung von privaten Profilen, den Upload von Fotos und eine Vernetzung \u00fcber Freundschaftsanfragen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft von Facebook ist die Facebook, Inc., 1 Hacker Way, Menlo Park, CA 94025, USA. F\u00fcr die Verarbeitung personenbezogener Daten Verantwortlicher ist, wenn eine betroffene Person au\u00dferhalb der USA oder Kanada lebt, die Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Facebook-Komponente (Facebook-Plug-In) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Facebook-Komponente veranlasst, eine Darstellung der entsprechenden Facebook-Komponente von Facebook herunterzuladen. Eine Gesamt\u00fcbersicht \u00fcber alle Facebook-Plug-Ins kann unter https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE abgerufen werden. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Facebook Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Sofern die betroffene Person gleichzeitig bei Facebook eingeloggt ist, erkennt Facebook mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die Facebook-Komponente gesammelt und durch Facebook dem jeweiligen Facebook-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Facebook-Buttons, beispielsweise den \u201eGef\u00e4llt mir\u201c-Button, oder gibt die betroffene Person einen Kommentar ab, ordnet Facebook diese Information dem pers\u00f6nlichen Facebook-Benutzerkonto der betroffenen Person zu und speichert diese personenbezogenen Daten.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Facebook erh\u00e4lt \u00fcber die Facebook-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Facebook eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Facebook-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Facebook von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Facebook-Account ausloggt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die von Facebook ver\u00f6ffentlichte Datenrichtlinie, die unter https:\/\/de-de.facebook.com\/about\/privacy\/ abrufbar ist, gibt Aufschluss \u00fcber die Erhebung, Verarbeitung und Nutzung personenbezogener Daten durch Facebook. Ferner wird dort erl\u00e4utert, welche Einstellungsm\u00f6glichkeiten Facebook zum Schutz der Privatsph\u00e4re der betroffenen Person bietet. Zudem sind unterschiedliche Applikationen erh\u00e4ltlich, die es erm\u00f6glichen, eine Daten\u00fcbermittlung an Facebook zu unterdr\u00fccken. Solche Applikationen k\u00f6nnen durch die betroffene Person genutzt werden, um eine Daten\u00fcbermittlung an Facebook zu unterdr\u00fccken.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>14. Datenschutzbestimmungen zu Einsatz und Verwendung von Google AdSense<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Google AdSense integriert. Google AdSense ist ein Online-Dienst, \u00fcber welchen eine Vermittlung von Werbung auf Drittseiten erm\u00f6glicht wird. Google AdSense beruht auf einem Algorithmus, welcher die auf Drittseiten angezeigten Werbeanzeigen passend zu den Inhalten der jeweiligen Drittseite ausw\u00e4hlt. Google AdSense gestattet ein interessenbezogenes Targeting des Internetnutzers, welches mittels Generierung von individuellen Benutzerprofilen umgesetzt wird.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft der Google-AdSense-Komponente ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin, D04 E5W5, Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Der Zweck der Google-AdSense-Komponente ist die Einbindung von Werbeanzeigen auf unserer Internetseite. Google-AdSense setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Mit der Setzung des Cookies wird der Alphabet Inc. eine Analyse der Benutzung unserer Internetseite erm\u00f6glicht. Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Google-AdSense-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Google-AdSense-Komponente veranlasst, Daten zum Zwecke der Online-Werbung und der Abrechnung von Provisionen an die Alphabet Inc. zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt die Alphabet Inc. Kenntnis \u00fcber personenbezogene Daten, wie der IP-Adresse der betroffenen Person, die der Alphabet Inc. unter anderem dazu dienen, die Herkunft der Besucher und Klicks nachzuvollziehen und in der Folge Provisionsabrechnungen zu erm\u00f6glichen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass die Alphabet Inc. ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von der Alphabet Inc. bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Google AdSense verwendet zudem sogenannte Z\u00e4hlpixel. Ein Z\u00e4hlpixel ist eine Miniaturgrafik, die in Internetseiten eingebettet wird, um eine Logdatei-Aufzeichnung und eine Logdatei-Analyse zu erm\u00f6glichen, wodurch eine statistische Auswertung durchgef\u00fchrt werden kann. Anhand des eingebetteten Z\u00e4hlpixels kann die Alphabet Inc. erkennen, ob und wann eine Internetseite von einer betroffenen Person ge\u00f6ffnet wurde und welche Links von der betroffenen Person angeklickt wurden. Z\u00e4hlpixel dienen unter anderem dazu, den Besucherfluss einer Internetseite auszuwerten.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>\u00dcber Google AdSense werden personenbezogene Daten und Informationen, was auch die IP-Adresse umfasst und zur Erfassung und Abrechnung der angezeigten Werbeanzeigen notwendig ist, an die Alphabet Inc. in die Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden in den Vereinigten Staaten von Amerika gespeichert und verarbeitet. Die Alphabet Inc. gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Google-AdSense wird unter diesem Link https:\/\/www.google.de\/intl\/de\/adsense\/start\/ genauer erl\u00e4utert.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>15. Datenschutzbestimmungen zu Einsatz und Verwendung von Google Analytics (mit Anonymisierungsfunktion)<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite die Komponente Google Analytics (mit Anonymisierungsfunktion) integriert. Google Analytics ist ein Web-Analyse-Dienst. Web-Analyse ist die Erhebung, Sammlung und Auswertung von Daten \u00fcber das Verhalten von Besuchern von Internetseiten. Ein Web-Analyse-Dienst erfasst unter anderem Daten dar\u00fcber, von welcher Internetseite eine betroffene Person auf eine Internetseite gekommen ist (sogenannte Referrer), auf welche Unterseiten der Internetseite zugegriffen oder wie oft und f\u00fcr welche Verweildauer eine Unterseite betrachtet wurde. Eine Web-Analyse wird \u00fcberwiegend zur Optimierung einer Internetseite und zur Kosten-Nutzen-Analyse von Internetwerbung eingesetzt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft der Google-Analytics-Komponente ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin, D04 E5W5, Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche verwendet f\u00fcr die Web-Analyse \u00fcber Google Analytics den Zusatz &#8222;_gat._anonymizeIp&#8220;. Mittels dieses Zusatzes wird die IP-Adresse des Internetanschlusses der betroffenen Person von Google gek\u00fcrzt und anonymisiert, wenn der Zugriff auf unsere Internetseiten aus einem Mitgliedstaat der Europ\u00e4ischen Union oder aus einem anderen Vertragsstaat des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum erfolgt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Der Zweck der Google-Analytics-Komponente ist die Analyse der Besucherstr\u00f6me auf unserer Internetseite. Google nutzt die gewonnenen Daten und Informationen unter anderem dazu, die Nutzung unserer Internetseite auszuwerten, um f\u00fcr uns Online-Reports, welche die Aktivit\u00e4ten auf unseren Internetseiten aufzeigen, zusammenzustellen, und um weitere mit der Nutzung unserer Internetseite in Verbindung stehende Dienstleistungen zu erbringen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Google Analytics setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Mit Setzung des Cookies wird Google eine Analyse der Benutzung unserer Internetseite erm\u00f6glicht. Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Google-Analytics-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Google-Analytics-Komponente veranlasst, Daten zum Zwecke der Online-Analyse an Google zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Google Kenntnis \u00fcber personenbezogene Daten, wie der IP-Adresse der betroffenen Person, die Google unter anderem dazu dienen, die Herkunft der Besucher und Klicks nachzuvollziehen und in der Folge Provisionsabrechnungen zu erm\u00f6glichen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Mittels des Cookies werden personenbezogene Informationen, beispielsweise die Zugriffszeit, der Ort, von welchem ein Zugriff ausging und die H\u00e4ufigkeit der Besuche unserer Internetseite durch die betroffene Person, gespeichert. Bei jedem Besuch unserer Internetseiten werden diese personenbezogenen Daten, einschlie\u00dflich der IP-Adresse des von der betroffenen Person genutzten Internetanschlusses, an Google in den Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden durch Google in den Vereinigten Staaten von Amerika gespeichert. Google gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von Google Analytics bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, einer Erfassung der durch Google Analytics erzeugten, auf eine Nutzung dieser Internetseite bezogenen Daten sowie der Verarbeitung dieser Daten durch Google zu widersprechen und eine solche zu verhindern. Hierzu muss die betroffene Person ein Browser-Add-On unter dem Link https:\/\/tools.google.com\/dlpage\/gaoptout herunterladen und installieren. Dieses Browser-Add-On teilt Google Analytics \u00fcber JavaScript mit, dass keine Daten und Informationen zu den Besuchen von Internetseiten an Google Analytics \u00fcbermittelt werden d\u00fcrfen. Die Installation des Browser-Add-Ons wird von Google als Widerspruch gewertet. Wird das informationstechnologische System der betroffenen Person zu einem sp\u00e4teren Zeitpunkt gel\u00f6scht, formatiert oder neu installiert, muss durch die betroffene Person eine erneute Installation des Browser-Add-Ons erfolgen, um Google Analytics zu deaktivieren. Sofern das Browser-Add-On durch die betroffene Person oder einer anderen Person, die ihrem Machtbereich zuzurechnen ist, deinstalliert oder deaktiviert wird, besteht die M\u00f6glichkeit der Neuinstallation oder der erneuten Aktivierung des Browser-Add-Ons.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ und unter http:\/\/www.google.com\/analytics\/terms\/de.html abgerufen werden. Google Analytics wird unter diesem Link https:\/\/www.google.com\/intl\/de_de\/analytics\/ genauer erl\u00e4utert.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>16. Datenschutzbestimmungen zu Einsatz und Verwendung von Google Remarketing<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Dienste von Google Remarketing integriert. Google Remarketing ist eine Funktion von Google-AdWords, die es einem Unternehmen erm\u00f6glicht, bei solchen Internetnutzern Werbung einblenden zu lassen, die sich zuvor auf der Internetseite des Unternehmens aufgehalten haben. Die Integration von Google Remarketing gestattet es einem Unternehmen demnach, nutzerbezogene Werbung zu erstellen und dem Internetnutzer folglich interessenrelevante Werbeanzeigen anzeigen zu lassen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft der Dienste von Google Remarketing ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin, D04 E5W5, Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Zweck von Google Remarketing ist die Einblendung von interessenrelevanter Werbung. Google Remarketing erm\u00f6glicht es uns, Werbeanzeigen \u00fcber das Google-Werbenetzwerk anzuzeigen oder auf anderen Internetseiten anzeigen zu lassen, welche auf die individuellen Bed\u00fcrfnisse und Interessen von Internetnutzern abgestimmt sind.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Google Remarketing setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Mit der Setzung des Cookies wird Google eine Wiedererkennung des Besuchers unserer Internetseite erm\u00f6glicht, wenn dieser in der Folge Internetseiten aufruft, die ebenfalls Mitglied des Google-Werbenetzwerks sind. Mit jedem Aufruf einer Internetseite, auf welcher der Dienst von Google Remarketing integriert wurde, identifiziert sich der Internetbrowser der betroffenen Person automatisch bei Google. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Google Kenntnis \u00fcber personenbezogene Daten, wie der IP-Adresse oder des Surfverhaltens des Nutzers, welche Google unter anderem zur Einblendung interessenrelevanter Werbung verwendet.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Mittels des Cookies werden personenbezogene Informationen, beispielsweise die durch die betroffene Person besuchten Internetseiten, gespeichert. Bei jedem Besuch unserer Internetseiten werden demnach personenbezogene Daten, einschlie\u00dflich der IP-Adresse des von der betroffenen Person genutzten Internetanschlusses, an Google in den Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden durch Google in den Vereinigten Staaten von Amerika gespeichert. Google gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von Google Analytics bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, der interessenbezogenen Werbung durch Google zu widersprechen. Hierzu muss die betroffene Person von jedem der von ihr genutzten Internetbrowser aus den Link www.google.de\/settings\/ads aufrufen und dort die gew\u00fcnschten Einstellungen vornehmen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ abgerufen werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>17. Datenschutzbestimmungen zu Einsatz und Verwendung von Google+<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite als Komponente die Google+ Schaltfl\u00e4che integriert. Google+ ist ein sogenanntes soziales Netzwerk. Ein soziales Netzwerk ist ein im Internet betriebener sozialer Treffpunkt, eine Online-Gemeinschaft, die es den Nutzern in der Regel erm\u00f6glicht, untereinander zu kommunizieren und im virtuellen Raum zu interagieren. Ein soziales Netzwerk kann als Plattform zum Austausch von Meinungen und Erfahrungen dienen oder erm\u00f6glicht es der Internetgemeinschaft, pers\u00f6nliche oder unternehmensbezogene Informationen bereitzustellen. Google+ erm\u00f6glicht den Nutzern des sozialen Netzwerkes unter anderem die Erstellung von privaten Profilen, den Upload von Fotos und eine Vernetzung \u00fcber Freundschaftsanfragen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft von Google+ ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin, D04 E5W5, Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Google+ Schaltfl\u00e4che integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Google+ Schaltfl\u00e4che veranlasst, eine Darstellung der entsprechenden Google+ Schaltfl\u00e4che von Google herunterzuladen. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Google Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird. Genauere Informationen zu Google+ sind unter https:\/\/developers.google.com\/+\/ abrufbar.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Sofern die betroffene Person gleichzeitig bei Google+ eingeloggt ist, erkennt Google mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die Google+ Schaltfl\u00e4che gesammelt und durch Google dem jeweiligen Google+-Account der betroffenen Person zugeordnet.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Google+-Buttons und gibt damit eine Google+1 Empfehlung ab, ordnet Google diese Information dem pers\u00f6nlichen Google+-Benutzerkonto der betroffenen Person zu und speichert diese personenbezogenen Daten. Google speichert die Google+1-Empfehlung der betroffenen Person und macht diese in \u00dcbereinstimmung mit den von der betroffenen Person diesbez\u00fcglich akzeptierten Bedingungen \u00f6ffentlich zug\u00e4nglich. Eine von der betroffenen Person auf dieser Internetseite abgegebene Google+1-Empfehlung wird in der Folge zusammen mit anderen personenbezogenen Daten, wie dem Namen des von der betroffenen Person genutzten Google+1-Accounts und dem in diesem hinterlegten Foto in anderen Google-Diensten, beispielsweise den Suchmaschinenergebnissen der Google-Suchmaschine, dem Google-Konto der betroffenen Person oder an sonstigen Stellen, beispielsweise auf Internetseiten oder im Zusammenhang mit Werbeanzeigen, gespeichert und verarbeitet. Ferner ist Google in der Lage, den Besuch auf dieser Internetseite mit anderen bei Google gespeicherten personenbezogenen Daten zu verkn\u00fcpfen. Google zeichnet diese personenbezogenen Informationen ferner mit dem Zweck auf, die unterschiedlichen Dienste von Google zu verbessern oder zu optimieren.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Google erh\u00e4lt \u00fcber die Google+-Schaltfl\u00e4che immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Google+ eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Google+-Schaltfl\u00e4che anklickt oder nicht.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Ist eine \u00dcbermittlung personenbezogener Daten an Google von der betroffenen Person nicht gewollt, kann diese eine solche \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Google+-Account ausloggt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ abgerufen werden. Weitere Hinweise von Google zur Google+1-Schaltfl\u00e4che k\u00f6nnen unter https:\/\/developers.google.com\/+\/web\/buttons-policy abgerufen werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>18. Datenschutzbestimmungen zu Einsatz und Verwendung von Google-AdWords<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Google AdWords integriert. Google AdWords ist ein Dienst zur Internetwerbung, der es Werbetreibenden gestattet, sowohl Anzeigen in den Suchmaschinenergebnissen von Google als auch im Google-Werbenetzwerk zu schalten. Google AdWords erm\u00f6glicht es einem Werbetreibenden, vorab bestimmte Schl\u00fcsselw\u00f6rter festzulegen, mittels derer eine Anzeige in den Suchmaschinenergebnissen von Google ausschlie\u00dflich dann angezeigt wird, wenn der Nutzer mit der Suchmaschine ein schl\u00fcsselwortrelevantes Suchergebnis abruft. Im Google-Werbenetzwerk werden die Anzeigen mittels eines automatischen Algorithmus und unter Beachtung der zuvor festgelegten Schl\u00fcsselw\u00f6rter auf themenrelevanten Internetseiten verteilt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft der Dienste von Google AdWords ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin, D04 E5W5, Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Der Zweck von Google AdWords ist die Bewerbung unserer Internetseite durch die Einblendung von interessenrelevanter Werbung auf den Internetseiten von Drittunternehmen und in den Suchmaschinenergebnissen der Suchmaschine Google und eine Einblendung von Fremdwerbung auf unserer Internetseite.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Gelangt eine betroffene Person \u00fcber eine Google-Anzeige auf unsere Internetseite, wird auf dem informationstechnologischen System der betroffenen Person durch Google ein sogenannter Conversion-Cookie abgelegt. Was Cookies sind, wurde oben bereits erl\u00e4utert. Ein Conversion-Cookie verliert nach drei\u00dfig Tagen seine G\u00fcltigkeit und dient nicht zur Identifikation der betroffenen Person. \u00dcber den Conversion-Cookie wird, sofern das Cookie noch nicht abgelaufen ist, nachvollzogen, ob bestimmte Unterseiten, beispielsweise der Warenkorb von einem Online-Shop-System, auf unserer Internetseite aufgerufen wurden. Durch den Conversion-Cookie k\u00f6nnen sowohl wir als auch Google nachvollziehen, ob eine betroffene Person, die \u00fcber eine AdWords-Anzeige auf unsere Internetseite gelangt ist, einen Umsatz generierte, also einen Warenkauf vollzogen oder abgebrochen hat.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die durch die Nutzung des Conversion-Cookies erhobenen Daten und Informationen werden von Google verwendet, um Besuchsstatistiken f\u00fcr unsere Internetseite zu erstellen. Diese Besuchsstatistiken werden durch uns wiederum genutzt, um die Gesamtanzahl der Nutzer zu ermitteln, welche \u00fcber AdWords-Anzeigen an uns vermittelt wurden, also um den Erfolg oder Misserfolg der jeweiligen AdWords-Anzeige zu ermitteln und um unsere AdWords-Anzeigen f\u00fcr die Zukunft zu optimieren. Weder unser Unternehmen noch andere Werbekunden von Google-AdWords erhalten Informationen von Google, mittels derer die betroffene Person identifiziert werden k\u00f6nnte.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Mittels des Conversion-Cookies werden personenbezogene Informationen, beispielsweise die durch die betroffene Person besuchten Internetseiten, gespeichert. Bei jedem Besuch unserer Internetseiten werden demnach personenbezogene Daten, einschlie\u00dflich der IP-Adresse des von der betroffenen Person genutzten Internetanschlusses, an Google in den Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden durch Google in den Vereinigten Staaten von Amerika gespeichert. Google gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google einen Conversion-Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von Google AdWords bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, der interessenbezogenen Werbung durch Google zu widersprechen. Hierzu muss die betroffene Person von jedem der von ihr genutzten Internetbrowser aus den Link www.google.de\/settings\/ads aufrufen und dort die gew\u00fcnschten Einstellungen vornehmen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ abgerufen werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>19. Datenschutzbestimmungen zu Einsatz und Verwendung von Instagram<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten des Dienstes Instagram integriert. Instagram ist ein Dienst, der als audiovisuelle Plattform zu qualifizieren ist und den Nutzern das Teilen von Fotos und Videos und zudem eine Weiterverbreitung solcher Daten in anderen sozialen Netzwerken erm\u00f6glicht.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft der Dienste von Instagram ist die Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2 Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Instagram-Komponente (Insta-Button) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Instagram-Komponente veranlasst, eine Darstellung der entsprechenden Komponente von Instagram herunterzuladen. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Instagram Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Sofern die betroffene Person gleichzeitig bei Instagram eingeloggt ist, erkennt Instagram mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite die betroffene Person besucht. Diese Informationen werden durch die Instagram-Komponente gesammelt und durch Instagram dem jeweiligen Instagram-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Instagram-Buttons, werden die damit \u00fcbertragenen Daten und Informationen dem pers\u00f6nlichen Instagram-Benutzerkonto der betroffenen Person zugeordnet und von Instagram gespeichert und verarbeitet.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Instagram erh\u00e4lt \u00fcber die Instagram-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Instagram eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Instagram-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Instagram von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Instagram-Account ausloggt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Instagram k\u00f6nnen unter https:\/\/help.instagram.com\/155833707900388 und https:\/\/www.instagram.com\/about\/legal\/privacy\/ abgerufen werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>20. Datenschutzbestimmungen zu Einsatz und Verwendung von LinkedIn<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten der LinkedIn Corporation integriert. LinkedIn ist ein Internetbasiertes soziales Netzwerk, das eine Konnektierung der Nutzer mit bestehenden Gesch\u00e4ftskontakten sowie das Kn\u00fcpfen von neuen Businesskontakten erm\u00f6glicht. \u00dcber 400 Millionen registrierte Personen nutzen LinkedIn in mehr als 200 L\u00e4ndern. Damit ist LinkedIn derzeit die gr\u00f6\u00dfte Plattform f\u00fcr Businesskontakte und eine der meistbesuchten Internetseiten der Welt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft von LinkedIn ist die LinkedIn Corporation, 2029 Stierlin Court Mountain View, CA 94043, USA. F\u00fcr Datenschutzangelegenheiten au\u00dferhalb der USA ist LinkedIn Ireland, Privacy Policy Issues, Wilton Plaza, Wilton Place, Dublin 2, Ireland, zust\u00e4ndig.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Bei jedem einzelnen Abruf unserer Internetseite, die mit einer LinkedIn-Komponente (LinkedIn-Plug-In) ausgestattet ist, veranlasst diese Komponente, dass der von der betroffenen Person verwendete Browser eine entsprechende Darstellung der Komponente von LinkedIn herunterl\u00e4dt. Weitere Informationen zu den LinkedIn-Plug-Ins k\u00f6nnen unter https:\/\/developer.linkedin.com\/plugins abgerufen werden. Im Rahmen dieses technischen Verfahrens erh\u00e4lt LinkedIn Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Sofern die betroffene Person gleichzeitig bei LinkedIn eingeloggt ist, erkennt LinkedIn mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die LinkedIn-Komponente gesammelt und durch LinkedIn dem jeweiligen LinkedIn-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen auf unserer Internetseite integrierten LinkedIn-Button, ordnet LinkedIn diese Information dem pers\u00f6nlichen LinkedIn-Benutzerkonto der betroffenen Person zu und speichert diese personenbezogenen Daten.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>LinkedIn erh\u00e4lt \u00fcber die LinkedIn-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufes unserer Internetseite gleichzeitig bei LinkedIn eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die LinkedIn-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an LinkedIn von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem LinkedIn-Account ausloggt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>LinkedIn bietet unter https:\/\/www.linkedin.com\/psettings\/guest-controls die M\u00f6glichkeit, E-Mail-Nachrichten, SMS-Nachrichten und zielgerichtete Anzeigen abzubestellen sowie Anzeigen-Einstellungen zu verwalten. LinkedIn nutzt ferner Partner wie Quantcast, Google Analytics, BlueKai, DoubleClick, Nielsen, Comscore, Eloqua und Lotame, die Cookies setzen k\u00f6nnen. Solche Cookies k\u00f6nnen unter https:\/\/www.linkedin.com\/legal\/cookie-policy abgelehnt werden. Die geltenden Datenschutzbestimmungen von LinkedIn sind unter https:\/\/www.linkedin.com\/legal\/privacy-policy abrufbar. Die Cookie-Richtlinie von LinkedIn ist unter https:\/\/www.linkedin.com\/legal\/cookie-policy abrufbar.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>21. Datenschutzbestimmungen zu Einsatz und Verwendung von Pinterest<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten der Pinterest Inc. integriert. Pinterest ist ein sogenanntes soziales Netzwerk. Ein soziales Netzwerk ist ein im Internet betriebener sozialer Treffpunkt, eine Online-Gemeinschaft, die es den Nutzern in der Regel erm\u00f6glicht, untereinander zu kommunizieren und im virtuellen Raum zu interagieren. Ein soziales Netzwerk kann als Plattform zum Austausch von Meinungen und Erfahrungen dienen oder erm\u00f6glicht es der Internetgemeinschaft, pers\u00f6nliche oder unternehmensbezogene Informationen bereitzustellen. Pinterest erm\u00f6glicht den Nutzern des sozialen Netzwerkes unter anderem, Bilderkollektionen und Einzelbilder sowie Beschreibungen an virtuellen Pinnw\u00e4nden zu ver\u00f6ffentlichen (sogenanntes pinnen), welche dann wiederum von anderen Nutzern geteilt (sogenanntes repinnen) oder kommentiert werden k\u00f6nnen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft von Pinterest ist die Pinterest Europe Ltd., Palmerston House, 2nd Floor, Fenian Street, Dublin 2,Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Pinterest-Komponente (Pinterest-Plug-In) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Pinterest-Komponente veranlasst, eine Darstellung der entsprechenden Pinterest-Komponente von Pinterest herunterzuladen. Mehr Informationen zu Pinterest sind unter https:\/\/pinterest.com\/ abrufbar. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Pinterest Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Sofern die betroffene Person gleichzeitig bei Pinterest eingeloggt ist, erkennt Pinterest mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die Pinterest-Komponente gesammelt und durch Pinterest dem jeweiligen Pinterest-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen auf unserer Internetseite integrierten Pinterest-Button, ordnet Pinterest diese Information dem pers\u00f6nlichen Pinterest-Benutzerkonto der betroffenen Person zu und speichert diese personenbezogenen Daten.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Pinterest erh\u00e4lt \u00fcber die Pinterest-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Pinterest eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Pinterest-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Pinterest von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Pinterest-Account ausloggt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die von Pinterest ver\u00f6ffentlichte Datenschutzrichtlinie, die unter https:\/\/about.pinterest.com\/privacy-policy abrufbar ist, gibt Aufschluss \u00fcber die Erhebung, Verarbeitung und Nutzung personenbezogener Daten durch Pinterest.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>22. Datenschutzbestimmungen zu Einsatz und Verwendung von Shariff<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite die Komponente Shariff integriert. Die Shariff-Komponente stellt Social-Media-Buttons zur Verf\u00fcgung, die datenschutzkonform sind. Shariff wurde f\u00fcr die deutsche Computerzeitschrift c&#8217;t entwickelt und wird \u00fcber die GitHub, Inc. publiziert.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Entwickler der Komponente ist GitHub, Inc. 88 Colin P. Kelly Junior Street, San Francisco, CA 94107, USA.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>\u00dcblicherweise \u00fcbertragen die von den sozialen Netzwerken bereitgestellten Button-L\u00f6sungen bereits dann personenbezogene Daten an das jeweilige soziale Netzwerk, wenn ein Nutzer eine Internetseite besucht, in welche ein Social-Media-Button integriert wurde. Durch die Nutzung der Shariff-Komponente werden erst dann personenbezogene Daten an soziale Netzwerke \u00fcbermittelt, wenn der Besucher einer Internetseite aktiv einen der Social-Media-Buttons bet\u00e4tigt. Weitere Informationen zur Shariff-Komponente werden von der Computerzeitschrift c&#8217;t unter http:\/\/www.heise.de\/newsticker\/meldung\/Datenschutz-und-Social-Media-Der-c-t-Shariff-ist-im-Einsatz-2470103.html bereitgehalten. Der Einsatz der Shariff-Komponente hat den Zweck, die personenbezogenen Daten der Besucher unserer Internetseite zu sch\u00fctzen und uns gleichzeitig zu erm\u00f6glichen, eine Button-L\u00f6sung f\u00fcr soziale Netzwerke auf dieser Internetseite zu integrieren.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von GitHub k\u00f6nnen unter https:\/\/help.github.com\/articles\/github-privacy-policy\/ abgerufen werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>23. Datenschutzbestimmungen zu Einsatz und Verwendung von YouTube<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von YouTube integriert. YouTube ist ein Internet-Videoportal, dass Video-Publishern das kostenlose Einstellen von Videoclips und anderen Nutzern die ebenfalls kostenfreie Betrachtung, Bewertung und Kommentierung dieser erm\u00f6glicht. YouTube gestattet die Publikation aller Arten von Videos, weshalb sowohl komplette Film- und Fernsehsendungen, aber auch Musikvideos, Trailer oder von Nutzern selbst angefertigte Videos \u00fcber das Internetportal abrufbar sind.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft von YouTube ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin, D04 E5W5, Ireland.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine YouTube-Komponente (YouTube-Video) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige YouTube-Komponente veranlasst, eine Darstellung der entsprechenden YouTube-Komponente von YouTube herunterzuladen. Weitere Informationen zu YouTube k\u00f6nnen unter https:\/\/www.youtube.com\/yt\/about\/de\/ abgerufen werden. Im Rahmen dieses technischen Verfahrens erhalten YouTube und Google Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Sofern die betroffene Person gleichzeitig bei YouTube eingeloggt ist, erkennt YouTube mit dem Aufruf einer Unterseite, die ein YouTube-Video enth\u00e4lt, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch YouTube und Google gesammelt und dem jeweiligen YouTube-Account der betroffenen Person zugeordnet.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>YouTube und Google erhalten \u00fcber die YouTube-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei YouTube eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person ein YouTube-Video anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an YouTube und Google von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem YouTube-Account ausloggt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die von YouTube ver\u00f6ffentlichten Datenschutzbestimmungen, die unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ abrufbar sind, geben Aufschluss \u00fcber die Erhebung, Verarbeitung und Nutzung personenbezogener Daten durch YouTube und Google.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>24. Zahlungsart: Datenschutzbestimmungen zu Klarna als Zahlungsart<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von Klarna integriert. Klarna ist ein Online-Zahlungsdienstleister, der den Kauf auf Rechnung oder eine flexible Ratenzahlung erm\u00f6glicht. Ferner werden von Klarna weitere Services, wie beispielsweise ein K\u00e4uferschutz oder eine Identit\u00e4ts- und Bonit\u00e4tspr\u00fcfung, angeboten.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft von Klarna ist die Klarna Bank AB, Sveav\u00e4gen 46, 111 34 Stockholm, Schweden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>W\u00e4hlt die betroffene Person w\u00e4hrend des Bestellvorgangs in unserem Online-Shop als Zahlungsm\u00f6glichkeit entweder den \u201eKauf auf Rechnung\u201c oder \u201eRatenkauf\u201c aus, werden automatisiert Daten der betroffenen Person an Klarna \u00fcbermittelt. Mit der Auswahl einer dieser Zahlungsoptionen willigt die betroffene Person in diese, zur Abwicklung des Rechnungs- oder Ratenkaufes oder zur Identit\u00e4ts- und Bonit\u00e4tspr\u00fcfung erforderliche, \u00dcbermittlung personenbezogener Daten ein.\u00a0<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Bei den an Klarna \u00fcbermittelten personenbezogenen Daten handelt es sich in der Regel um Vorname, Nachname, Adresse, Geburtsdatum, Geschlecht, Email-Adresse, IP-Adresse, Telefonnummer, Mobiltelefonnummer sowie um andere Daten, die zur Abwicklung eines Rechnungs- oder Ratenkaufs notwendig sind. Zur Abwicklung des Kaufvertrages notwendig sind auch solche personenbezogenen Daten, die im Zusammenhang mit der jeweiligen Bestellung stehen. Insbesondere kann es zum wechselseitigen Austausch von Zahlungsinformationen, wie Bankverbindung, Kartennummer, G\u00fcltigkeitsdatum und CVC-Code, Artikelanzahl, Artikelnummer, Daten zu Waren und Dienstleistungen, Preise und steuerliche Abgaben, Angaben zum fr\u00fcheren Kaufverhalten oder sonstige Angaben zur finanziellen Situation der betroffenen Person, kommen.\u00a0<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die \u00dcbermittlung der Daten bezweckt insbesondere die Identit\u00e4ts\u00fcberpr\u00fcfung, die Zahlungsadministration und die Betrugspr\u00e4vention. Der f\u00fcr die Verarbeitung Verantwortliche wird Klarna personenbezogene Daten insbesondere dann \u00fcbermitteln, wenn ein berechtigtes Interesse f\u00fcr die \u00dcbermittlung gegeben ist. Die zwischen Klarna und dem f\u00fcr die Verarbeitung Verantwortlichen ausgetauschten personenbezogenen Daten werden von Klarna an Wirtschaftsauskunfteien \u00fcbermittelt. Diese \u00dcbermittlung bezweckt die Identit\u00e4ts- und Bonit\u00e4tspr\u00fcfung.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Klarna gibt die personenbezogenen Daten auch an verbundene Unternehmen (Klarna Gruppe) und Leistungserbringer oder Subunternehmer weiter, soweit dies zur Erf\u00fcllung der vertraglichen Verpflichtungen erforderlich ist oder die Daten im Auftrag verarbeitet werden sollen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Zur Entscheidung \u00fcber die Begr\u00fcndung, Durchf\u00fchrung oder Beendigung einer Vertragsbeziehung erhebt und nutzt Klarna Daten und Informationen \u00fcber das bisherige Zahlungsverhalten der betroffenen Person sowie Wahrscheinlichkeitswerte f\u00fcr deren Verhalten in der Zukunft (sogenanntes Scoring). Die Berechnung des Scorings wird auf der Basis wissenschaftlich anerkannter mathematisch-statistischer Verfahren durchgef\u00fchrt.\u00a0<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die betroffene Person hat die M\u00f6glichkeit, die Einwilligung zum Umgang mit personenbezogenen Daten jederzeit gegen\u00fcber Klarna zu widerrufen. Ein Widerruf wirkt sich nicht auf personenbezogene Daten aus, die zwingend zur (vertragsgem\u00e4\u00dfen) Zahlungsabwicklung verarbeitet, genutzt oder \u00fcbermittelt werden m\u00fcssen.\u00a0<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die geltenden Datenschutzbestimmungen von Klarna k\u00f6nnen unter https:\/\/cdn.klarna.com\/1.0\/shared\/content\/policy\/data\/de_de\/data_protection.pdf abgerufen werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>25. Zahlungsart: Datenschutzbestimmungen zu PayPal als Zahlungsart<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von PayPal integriert. PayPal ist ein Online-Zahlungsdienstleister. Zahlungen werden \u00fcber sogenannte PayPal-Konten abgewickelt, die virtuelle Privat- oder Gesch\u00e4ftskonten darstellen. Zudem besteht bei PayPal die M\u00f6glichkeit, virtuelle Zahlungen \u00fcber Kreditkarten abzuwickeln, wenn ein Nutzer kein PayPal-Konto unterh\u00e4lt. Ein PayPal-Konto wird \u00fcber eine E-Mail-Adresse gef\u00fchrt, weshalb es keine klassische Kontonummer gibt. PayPal erm\u00f6glicht es, Online-Zahlungen an Dritte auszul\u00f6sen oder auch Zahlungen zu empfangen. PayPal \u00fcbernimmt ferner Treuh\u00e4nderfunktionen und bietet K\u00e4uferschutzdienste an.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die Europ\u00e4ische Betreibergesellschaft von PayPal ist die PayPal (Europe) S.\u00e0.r.l. et Cie, S.C.A., 22-24 Boulevard Royal L-2449, Luxemburg.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>W\u00e4hlt die betroffene Person w\u00e4hrend des Bestellvorgangs in unserem Online-Shop als Zahlungsm\u00f6glichkeit \u201ePayPal\u201c aus, werden automatisiert Daten der betroffenen Person an PayPal \u00fcbermittelt. Mit der Auswahl dieser Zahlungsoption willigt die betroffene Person in die zur Zahlungsabwicklung erforderliche \u00dcbermittlung personenbezogener Daten ein.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Bei den an PayPal \u00fcbermittelten personenbezogenen Daten handelt es sich in der Regel um Vorname, Nachname, Adresse, Email-Adresse, IP-Adresse, Telefonnummer, Mobiltelefonnummer oder andere Daten, die zur Zahlungsabwicklung notwendig sind. Zur Abwicklung des Kaufvertrages notwendig sind auch solche personenbezogenen Daten, die im Zusammenhang mit der jeweiligen Bestellung stehen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die \u00dcbermittlung der Daten bezweckt die Zahlungsabwicklung und die Betrugspr\u00e4vention. Der f\u00fcr die Verarbeitung Verantwortliche wird PayPal personenbezogene Daten insbesondere dann \u00fcbermitteln, wenn ein berechtigtes Interesse f\u00fcr die \u00dcbermittlung gegeben ist. Die zwischen PayPal und dem f\u00fcr die Verarbeitung Verantwortlichen ausgetauschten personenbezogenen Daten werden von PayPal unter Umst\u00e4nden an Wirtschaftsauskunfteien \u00fcbermittelt. Diese \u00dcbermittlung bezweckt die Identit\u00e4ts- und Bonit\u00e4tspr\u00fcfung.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>PayPal gibt die personenbezogenen Daten gegebenenfalls an verbundene Unternehmen und Leistungserbringer oder Subunternehmer weiter, soweit dies zur Erf\u00fcllung der vertraglichen Verpflichtungen erforderlich ist oder die Daten im Auftrag verarbeitet werden sollen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die betroffene Person hat die M\u00f6glichkeit, die Einwilligung zum Umgang mit personenbezogenen Daten jederzeit gegen\u00fcber PayPal zu widerrufen. Ein Widerruf wirkt sich nicht auf personenbezogene Daten aus, die zwingend zur (vertragsgem\u00e4\u00dfen) Zahlungsabwicklung verarbeitet, genutzt oder \u00fcbermittelt werden m\u00fcssen.\u00a0<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die geltenden Datenschutzbestimmungen von PayPal k\u00f6nnen unter https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full abgerufen werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>26. Zahlungsart: Datenschutzbestimmungen zu Sofort\u00fcberweisung als Zahlungsart<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von Sofort\u00fcberweisung integriert. Sofort\u00fcberweisung ist ein Zahlungsdienst, der eine bargeldlose Zahlung von Produkten und Dienstleistungen im Internet erm\u00f6glicht. Sofort\u00fcberweisung bildet ein technisches Verfahren ab, durch welches der Online-H\u00e4ndler unverz\u00fcglich eine Zahlungsbest\u00e4tigung erh\u00e4lt. So wird ein H\u00e4ndler in die Lage versetzt, Waren, Dienstleistungen oder Downloads sofort nach der Bestellung an den Kunden auszuliefern.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Betreibergesellschaft von Sofort\u00fcberweisung ist die Klarna Bank AB, Sveav\u00e4gen 46, 111 34 Stockholm, Schweden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>W\u00e4hlt die betroffene Person w\u00e4hrend des Bestellvorgangs in unserem Online-Shop als Zahlungsm\u00f6glichkeit \u201eSofort\u00fcberweisung\u201c aus, werden automatisiert Daten der betroffenen Person an Sofort\u00fcberweisung \u00fcbermittelt. Mit einer Auswahl dieser Zahlungsoption willigt die betroffene Person in eine zur Zahlungsabwicklung erforderliche \u00dcbermittlung personenbezogener Daten ein.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Bei der Kaufabwicklung \u00fcber Sofort\u00fcberweisung \u00fcbermittelt der K\u00e4ufer die PIN und die TAN an die Sofort GmbH. Sofort\u00fcberweisung f\u00fchrt sodann nach technischer \u00dcberpr\u00fcfung des Kontostandes und Abruf weiterer Daten zur Pr\u00fcfung der Kontodeckung eine \u00dcberweisung an den Online-H\u00e4ndler aus. Die Durchf\u00fchrung der Finanztransaktion wird dem Online-H\u00e4ndler sodann automatisiert mitgeteilt.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Bei den mit Sofort\u00fcberweisung ausgetauschten personenbezogenen Daten handelt es sich um Vorname, Nachname, Adresse, Email-Adresse, IP-Adresse, Telefonnummer, Mobiltelefonnummer oder andere Daten, die zur Zahlungsabwicklung notwendig sind. Die \u00dcbermittlung der Daten bezweckt die Zahlungsabwicklung und die Betrugspr\u00e4vention. Der f\u00fcr die Verarbeitung Verantwortliche wird Sofort\u00fcberweisung andere personenbezogene Daten auch dann \u00fcbermitteln, wenn ein berechtigtes Interesse f\u00fcr die \u00dcbermittlung gegeben ist. Die zwischen Sofort\u00fcberweisung und dem f\u00fcr die Verarbeitung Verantwortlichen ausgetauschten personenbezogenen Daten werden von Sofort\u00fcberweisung unter Umst\u00e4nden an Wirtschaftsauskunfteien \u00fcbermittelt. Diese \u00dcbermittlung bezweckt die Identit\u00e4ts- und Bonit\u00e4tspr\u00fcfung.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Sofort\u00fcberweisung gibt die personenbezogenen Daten gegebenenfalls an verbundene Unternehmen und Leistungserbringer oder Subunternehmer weiter, soweit dies zur Erf\u00fcllung der vertraglichen Verpflichtungen erforderlich ist oder die Daten im Auftrag verarbeitet werden sollen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die betroffene Person hat die M\u00f6glichkeit, die Einwilligung zum Umgang mit personenbezogenen Daten jederzeit gegen\u00fcber Sofort\u00fcberweisung zu widerrufen. Ein Widerruf wirkt sich nicht auf personenbezogene Daten aus, die zwingend zur (vertragsgem\u00e4\u00dfen) Zahlungsabwicklung verarbeitet, genutzt oder \u00fcbermittelt werden m\u00fcssen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Die geltenden Datenschutzbestimmungen von Sofort\u00fcberweisung k\u00f6nnen unter https:\/\/www.klarna.com\/sofort\/datenschutz\/ abgerufen werden.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>27. Rechtsgrundlage der Verarbeitung<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Art. 6 I lit. a DS-GVO dient unserem Unternehmen als Rechtsgrundlage f\u00fcr Verarbeitungsvorg\u00e4nge, bei denen wir eine Einwilligung f\u00fcr einen bestimmten Verarbeitungszweck einholen. Ist die Verarbeitung personenbezogener Daten zur Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, erforderlich, wie dies beispielsweise bei Verarbeitungsvorg\u00e4ngen der Fall ist, die f\u00fcr eine Lieferung von Waren oder die Erbringung einer sonstigen Leistung oder Gegenleistung notwendig sind, so beruht die Verarbeitung auf Art. 6 I lit. b DS-GVO. Gleiches gilt f\u00fcr solche Verarbeitungsvorg\u00e4nge die zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich sind, etwa in F\u00e4llen von Anfragen zur unseren Produkten oder Leistungen. Unterliegt unser Unternehmen einer rechtlichen Verpflichtung durch welche eine Verarbeitung von personenbezogenen Daten erforderlich wird, wie beispielsweise zur Erf\u00fcllung steuerlicher Pflichten, so basiert die Verarbeitung auf Art. 6 I lit. c DS-GVO. In seltenen F\u00e4llen k\u00f6nnte die Verarbeitung von personenbezogenen Daten erforderlich werden, um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen. Dies w\u00e4re beispielsweise der Fall, wenn ein Besucher in unserem Betrieb verletzt werden w\u00fcrde und daraufhin sein Name, sein Alter, seine Krankenkassendaten oder sonstige lebenswichtige Informationen an einen Arzt, ein Krankenhaus oder sonstige Dritte weitergegeben werden m\u00fcssten. Dann w\u00fcrde die Verarbeitung auf Art. 6 I lit. d DS-GVO beruhen. Letztlich k\u00f6nnten Verarbeitungsvorg\u00e4nge auf Art. 6 I lit. f DS-GVO beruhen. Auf dieser Rechtsgrundlage basieren Verarbeitungsvorg\u00e4nge, die von keiner der vorgenannten Rechtsgrundlagen erfasst werden, wenn die Verarbeitung zur Wahrung eines berechtigten Interesses unseres Unternehmens oder eines Dritten erforderlich ist, sofern die Interessen, Grundrechte und Grundfreiheiten des Betroffenen nicht \u00fcberwiegen. Solche Verarbeitungsvorg\u00e4nge sind uns insbesondere deshalb gestattet, weil sie durch den Europ\u00e4ischen Gesetzgeber besonders erw\u00e4hnt wurden. Er vertrat insoweit die Auffassung, dass ein berechtigtes Interesse anzunehmen sein k\u00f6nnte, wenn die betroffene Person ein Kunde des Verantwortlichen ist (Erw\u00e4gungsgrund 47 Satz 2 DS-GVO).<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>28. Berechtigte Interessen an der Verarbeitung, die von dem Verantwortlichen oder einem Dritten verfolgt werden<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Basiert die Verarbeitung personenbezogener Daten auf Artikel 6 I lit. f DS-GVO ist unser berechtigtes Interesse die Durchf\u00fchrung unserer Gesch\u00e4ftst\u00e4tigkeit zugunsten des Wohlergehens all unserer Mitarbeiter und unserer Anteilseigner.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>29. Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Das Kriterium f\u00fcr die Dauer der Speicherung von personenbezogenen Daten ist die jeweilige gesetzliche Aufbewahrungsfrist. Nach Ablauf der Frist werden die entsprechenden Daten routinem\u00e4\u00dfig gel\u00f6scht, sofern sie nicht mehr zur Vertragserf\u00fcllung oder Vertragsanbahnung erforderlich sind.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>30. Gesetzliche oder vertragliche Vorschriften zur Bereitstellung der personenbezogenen Daten; Erforderlichkeit f\u00fcr den Vertragsabschluss; Verpflichtung der betroffenen Person, die personenbezogenen Daten bereitzustellen; m\u00f6gliche Folgen der Nichtbereitstellung<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Wir kl\u00e4ren Sie dar\u00fcber auf, dass die Bereitstellung personenbezogener Daten zum Teil gesetzlich vorgeschrieben ist (z.B. Steuervorschriften) oder sich auch aus vertraglichen Regelungen (z.B. Angaben zum Vertragspartner) ergeben kann. Mitunter kann es zu einem Vertragsschluss erforderlich sein, dass eine betroffene Person uns personenbezogene Daten zur Verf\u00fcgung stellt, die in der Folge durch uns verarbeitet werden m\u00fcssen. Die betroffene Person ist beispielsweise verpflichtet uns personenbezogene Daten bereitzustellen, wenn unser Unternehmen mit ihr einen Vertrag abschlie\u00dft. Eine Nichtbereitstellung der personenbezogenen Daten h\u00e4tte zur Folge, dass der Vertrag mit dem Betroffenen nicht geschlossen werden k\u00f6nnte. Vor einer Bereitstellung personenbezogener Daten durch den Betroffenen muss sich der Betroffene an einen unserer Mitarbeiter wenden. Unser Mitarbeiter kl\u00e4rt den Betroffenen einzelfallbezogen dar\u00fcber auf, ob die Bereitstellung der personenbezogenen Daten gesetzlich oder vertraglich vorgeschrieben oder f\u00fcr den Vertragsabschluss erforderlich ist, ob eine Verpflichtung besteht, die personenbezogenen Daten bereitzustellen, und welche Folgen die Nichtbereitstellung der personenbezogenen Daten h\u00e4tte.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":4} -->\n<h4>31. Bestehen einer automatisierten Entscheidungsfindung<\/h4>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Als verantwortungsbewusstes Unternehmen verzichten wir auf eine automatische Entscheidungsfindung oder ein Profiling.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Diese Datenschutzerkl\u00e4rung wurde durch den Datenschutzerkl\u00e4rungs-Generator der DGD Deutsche Gesellschaft f\u00fcr Datenschutz GmbH, die als <a href=\"https:\/\/dg-datenschutz.de\/datenschutz-dienstleistungen\/externer-datenschutzbeauftragter\/\">Externer Datenschutzbeauftragter Stuttgart<\/a> t\u00e4tig ist, in Kooperation mit dem <a href=\"https:\/\/www.wbs-law.de\/\">K\u00f6lner Datenschutz Anwalt Christian Solmecke<\/a> erstellt.<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der Angie Meyer. Eine Nutzung der Internetseiten der Angie Meyer ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-width","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"on","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutzerkl\u00e4rung - headshots-wiesbaden.com<\/title>\n<meta name=\"description\" content=\"Datenschutzerkl\u00e4rung Headshotfotografie in Wiesbaden, Frankfurt, Mainz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.headshots-wiesbaden.com\/en\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - headshots-wiesbaden.com\" \/>\n<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung Headshotfotografie in Wiesbaden, Frankfurt, Mainz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.headshots-wiesbaden.com\/en\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"headshots-wiesbaden.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/headshotfotografie.wiesbaden\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-07T13:17:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"61 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/\",\"url\":\"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/\",\"name\":\"Datenschutzerkl\u00e4rung - headshots-wiesbaden.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/#website\"},\"datePublished\":\"2020-08-13T03:27:38+00:00\",\"dateModified\":\"2024-10-07T13:17:04+00:00\",\"description\":\"Datenschutzerkl\u00e4rung Headshotfotografie in Wiesbaden, Frankfurt, Mainz.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.headshots-wiesbaden.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/#website\",\"url\":\"https:\/\/www.headshots-wiesbaden.com\/\",\"name\":\"angiemeyerfotografie.de\",\"description\":\"Headshotfotografie f\u00fcr Profile mit Pers\u00f6nlichkeit\",\"publisher\":{\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.headshots-wiesbaden.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/#organization\",\"name\":\"Angie Meyer Fotografie\",\"url\":\"https:\/\/www.headshots-wiesbaden.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.angiemeyerfotografie.de\/wp-content\/uploads\/2021\/02\/cropped-Favicon_2021.png\",\"contentUrl\":\"https:\/\/www.angiemeyerfotografie.de\/wp-content\/uploads\/2021\/02\/cropped-Favicon_2021.png\",\"width\":512,\"height\":512,\"caption\":\"Angie Meyer Fotografie\"},\"image\":{\"@id\":\"https:\/\/www.headshots-wiesbaden.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/headshotfotografie.wiesbaden\",\"https:\/\/www.instagram.com\/angiemeyer.photo\/\",\"https:\/\/www.linkedin.com\/in\/angie-meyer-891a361b0\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - headshots-wiesbaden.com","description":"Datenschutzerkl\u00e4rung Headshotfotografie in Wiesbaden, Frankfurt, Mainz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.headshots-wiesbaden.com\/en\/datenschutz\/","og_locale":"en_US","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - headshots-wiesbaden.com","og_description":"Datenschutzerkl\u00e4rung Headshotfotografie in Wiesbaden, Frankfurt, Mainz.","og_url":"https:\/\/www.headshots-wiesbaden.com\/en\/datenschutz\/","og_site_name":"headshots-wiesbaden.com","article_publisher":"https:\/\/www.facebook.com\/headshotfotografie.wiesbaden","article_modified_time":"2024-10-07T13:17:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"61 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/","url":"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/","name":"Datenschutzerkl\u00e4rung - headshots-wiesbaden.com","isPartOf":{"@id":"https:\/\/www.headshots-wiesbaden.com\/#website"},"datePublished":"2020-08-13T03:27:38+00:00","dateModified":"2024-10-07T13:17:04+00:00","description":"Datenschutzerkl\u00e4rung Headshotfotografie in Wiesbaden, Frankfurt, Mainz.","breadcrumb":{"@id":"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.headshots-wiesbaden.com\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.headshots-wiesbaden.com\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.headshots-wiesbaden.com\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/www.headshots-wiesbaden.com\/#website","url":"https:\/\/www.headshots-wiesbaden.com\/","name":"angiemeyerfotografie.de","description":"Headshotfotografie f\u00fcr Profile mit Pers\u00f6nlichkeit","publisher":{"@id":"https:\/\/www.headshots-wiesbaden.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.headshots-wiesbaden.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.headshots-wiesbaden.com\/#organization","name":"Angie Meyer Fotografie","url":"https:\/\/www.headshots-wiesbaden.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.headshots-wiesbaden.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.angiemeyerfotografie.de\/wp-content\/uploads\/2021\/02\/cropped-Favicon_2021.png","contentUrl":"https:\/\/www.angiemeyerfotografie.de\/wp-content\/uploads\/2021\/02\/cropped-Favicon_2021.png","width":512,"height":512,"caption":"Angie Meyer Fotografie"},"image":{"@id":"https:\/\/www.headshots-wiesbaden.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/headshotfotografie.wiesbaden","https:\/\/www.instagram.com\/angiemeyer.photo\/","https:\/\/www.linkedin.com\/in\/angie-meyer-891a361b0\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.headshots-wiesbaden.com\/en\/wp-json\/wp\/v2\/pages\/176"}],"collection":[{"href":"https:\/\/www.headshots-wiesbaden.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.headshots-wiesbaden.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.headshots-wiesbaden.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.headshots-wiesbaden.com\/en\/wp-json\/wp\/v2\/comments?post=176"}],"version-history":[{"count":0,"href":"https:\/\/www.headshots-wiesbaden.com\/en\/wp-json\/wp\/v2\/pages\/176\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.headshots-wiesbaden.com\/en\/wp-json\/wp\/v2\/media?parent=176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}